{"id":18100,"date":"2025-08-13T16:10:16","date_gmt":"2025-08-13T21:10:16","guid":{"rendered":"https:\/\/bastropstg.wpenginepowered.com\/?post_type=tribe_events&#038;p=18100"},"modified":"2025-08-28T21:41:46","modified_gmt":"2025-08-29T02:41:46","slug":"fe-en-movimiento-empoderar-a-los-jovenes-lideres","status":"publish","type":"tribe_events","link":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/","title":{"rendered":"Fe en movimiento &#8211; Empoderar a los j\u00f3venes l\u00edderes"},"content":{"rendered":"<p>J\u00f3venes de 13 a 24 a\u00f1os est\u00e1n invitados a participar en Fe en Movimiento, una iniciativa juvenil que busca fomentar la resiliencia, el liderazgo y el prop\u00f3sito. Este encuentro ofrece un ambiente de apoyo donde los j\u00f3venes pueden conectar, crecer y generar un impacto positivo en su comunidad. Este evento es la oportunidad perfecta para interactuar con mentores, desarrollar habilidades de liderazgo y generar un cambio significativo en su comunidad. Para m\u00e1s informaci\u00f3n, contacte con nuestra Directora de Resiliencia e Inclusi\u00f3n, Grace Georges, en grace@bastropcares.org.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00f3venes de 13 a 24 a\u00f1os est\u00e1n invitados a participar en Fe en Movimiento, una iniciativa juvenil que busca fomentar la resiliencia, el liderazgo y el prop\u00f3sito. Este encuentro ofrece [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":17813,"template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[182],"class_list":["post-18100","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-comunidades-prosperas","cat_comunidades-prosperas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fe en movimiento - Empoderar a los j\u00f3venes l\u00edderes - Bastrop County Cares<\/title>\n<meta name=\"description\" content=\"Participa en Fe en Movimiento, iniciativa juvenil para j\u00f3venes de 13 a 24 a\u00f1os que impulsa resiliencia, liderazgo y prop\u00f3sito. Conecta con mentores, desarrolla habilidades y genera impacto positivo en tu comunidad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fe en movimiento - Empoderar a los j\u00f3venes l\u00edderes - Bastrop County Cares\" \/>\n<meta property=\"og:description\" content=\"Participa en Fe en Movimiento, iniciativa juvenil para j\u00f3venes de 13 a 24 a\u00f1os que impulsa resiliencia, liderazgo y prop\u00f3sito. Conecta con mentores, desarrolla habilidades y genera impacto positivo en tu comunidad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/\" \/>\n<meta property=\"og:site_name\" content=\"Bastrop County Cares\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BastropCares\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T02:41:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bastropcares.org\/wp-content\/uploads\/2025\/05\/BA01228D-7D41-44D2-BFBD-1C511DFEB9CB.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/community-event\\\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\\\/\",\"url\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/community-event\\\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\\\/\",\"name\":\"Fe en movimiento - Empoderar a los j\u00f3venes l\u00edderes - Bastrop County Cares\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/community-event\\\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/community-event\\\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bastropcares.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/BA01228D-7D41-44D2-BFBD-1C511DFEB9CB.jpeg\",\"datePublished\":\"2025-08-13T21:10:16+00:00\",\"dateModified\":\"2025-08-29T02:41:46+00:00\",\"description\":\"Participa en Fe en Movimiento, iniciativa juvenil para j\u00f3venes de 13 a 24 a\u00f1os que impulsa resiliencia, liderazgo y prop\u00f3sito. Conecta con mentores, desarrolla habilidades y genera impacto positivo en tu comunidad\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/community-event\\\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/community-event\\\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/community-event\\\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bastropcares.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/BA01228D-7D41-44D2-BFBD-1C511DFEB9CB.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.bastropcares.org\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/BA01228D-7D41-44D2-BFBD-1C511DFEB9CB.jpeg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/community-event\\\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventos\",\"item\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/community-events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fe en movimiento &#8211; Empoderar a los j\u00f3venes l\u00edderes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/\",\"name\":\"Bastrop County Cares\",\"description\":\"Bastrop County Cares is a non-profit organization uniting communities in Bastrop County and central Texas through partnerships and collaborative efforts.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/#organization\",\"name\":\"Bastrop County Cares\",\"url\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.bastropcares.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Bastrop-County-Cares-Logo-STACKED-\u2014-V1.svg\",\"contentUrl\":\"https:\\\/\\\/www.bastropcares.org\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Bastrop-County-Cares-Logo-STACKED-\u2014-V1.svg\",\"width\":660,\"height\":269,\"caption\":\"Bastrop County Cares\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bastropcares.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/BastropCares\",\"https:\\\/\\\/www.instagram.com\\\/bastropcountycares\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fe en movimiento - Empoderar a los j\u00f3venes l\u00edderes - Bastrop County Cares","description":"Participa en Fe en Movimiento, iniciativa juvenil para j\u00f3venes de 13 a 24 a\u00f1os que impulsa resiliencia, liderazgo y prop\u00f3sito. Conecta con mentores, desarrolla habilidades y genera impacto positivo en tu comunidad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/","og_locale":"es_ES","og_type":"article","og_title":"Fe en movimiento - Empoderar a los j\u00f3venes l\u00edderes - Bastrop County Cares","og_description":"Participa en Fe en Movimiento, iniciativa juvenil para j\u00f3venes de 13 a 24 a\u00f1os que impulsa resiliencia, liderazgo y prop\u00f3sito. Conecta con mentores, desarrolla habilidades y genera impacto positivo en tu comunidad","og_url":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/","og_site_name":"Bastrop County Cares","article_publisher":"https:\/\/www.facebook.com\/BastropCares","article_modified_time":"2025-08-29T02:41:46+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.bastropcares.org\/wp-content\/uploads\/2025\/05\/BA01228D-7D41-44D2-BFBD-1C511DFEB9CB.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/","url":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/","name":"Fe en movimiento - Empoderar a los j\u00f3venes l\u00edderes - Bastrop County Cares","isPartOf":{"@id":"https:\/\/www.bastropcares.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/#primaryimage"},"image":{"@id":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bastropcares.org\/wp-content\/uploads\/2025\/05\/BA01228D-7D41-44D2-BFBD-1C511DFEB9CB.jpeg","datePublished":"2025-08-13T21:10:16+00:00","dateModified":"2025-08-29T02:41:46+00:00","description":"Participa en Fe en Movimiento, iniciativa juvenil para j\u00f3venes de 13 a 24 a\u00f1os que impulsa resiliencia, liderazgo y prop\u00f3sito. Conecta con mentores, desarrolla habilidades y genera impacto positivo en tu comunidad","breadcrumb":{"@id":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/#primaryimage","url":"https:\/\/www.bastropcares.org\/wp-content\/uploads\/2025\/05\/BA01228D-7D41-44D2-BFBD-1C511DFEB9CB.jpeg","contentUrl":"https:\/\/www.bastropcares.org\/wp-content\/uploads\/2025\/05\/BA01228D-7D41-44D2-BFBD-1C511DFEB9CB.jpeg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.bastropcares.org\/es\/community-event\/fe-en-movimiento-empoderar-a-los-jovenes-lideres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bastropcares.org\/es\/"},{"@type":"ListItem","position":2,"name":"Eventos","item":"https:\/\/www.bastropcares.org\/es\/community-events\/"},{"@type":"ListItem","position":3,"name":"Fe en movimiento &#8211; Empoderar a los j\u00f3venes l\u00edderes"}]},{"@type":"WebSite","@id":"https:\/\/www.bastropcares.org\/es\/#website","url":"https:\/\/www.bastropcares.org\/es\/","name":"Bastrop County Cares","description":"Bastrop County Cares is a non-profit organization uniting communities in Bastrop County and central Texas through partnerships and collaborative efforts.","publisher":{"@id":"https:\/\/www.bastropcares.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bastropcares.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.bastropcares.org\/es\/#organization","name":"Bastrop County Cares","url":"https:\/\/www.bastropcares.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.bastropcares.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.bastropcares.org\/wp-content\/uploads\/2025\/02\/Bastrop-County-Cares-Logo-STACKED-\u2014-V1.svg","contentUrl":"https:\/\/www.bastropcares.org\/wp-content\/uploads\/2025\/02\/Bastrop-County-Cares-Logo-STACKED-\u2014-V1.svg","width":660,"height":269,"caption":"Bastrop County Cares"},"image":{"@id":"https:\/\/www.bastropcares.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BastropCares","https:\/\/www.instagram.com\/bastropcountycares\/"]}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.bastropcares.org\/es\/wp-json\/wp\/v2\/tribe_events\/18100","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bastropcares.org\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.bastropcares.org\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.bastropcares.org\/es\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":0,"href":"https:\/\/www.bastropcares.org\/es\/wp-json\/wp\/v2\/tribe_events\/18100\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bastropcares.org\/es\/wp-json\/wp\/v2\/media\/17813"}],"wp:attachment":[{"href":"https:\/\/www.bastropcares.org\/es\/wp-json\/wp\/v2\/media?parent=18100"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bastropcares.org\/es\/wp-json\/wp\/v2\/tags?post=18100"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.bastropcares.org\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=18100"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}